{"id":4006,"date":"2026-07-08T22:02:42","date_gmt":"2026-07-09T01:02:42","guid":{"rendered":"https:\/\/canalsamba.sitetopfm.com.br\/site\/comissao-aprova-projeto-que-reforca-prioridade-de-atendimento-para-cuidadores-de-pessoas-com-deficiencia-noticias\/"},"modified":"2026-07-08T22:02:42","modified_gmt":"2026-07-09T01:02:42","slug":"comissao-aprova-projeto-que-reforca-prioridade-de-atendimento-para-cuidadores-de-pessoas-com-deficiencia-noticias","status":"publish","type":"post","link":"https:\/\/canalsamba.sitetopfm.com.br\/site\/comissao-aprova-projeto-que-reforca-prioridade-de-atendimento-para-cuidadores-de-pessoas-com-deficiencia-noticias\/","title":{"rendered":"Comiss\u00e3o aprova projeto que refor\u00e7a prioridade de atendimento para cuidadores de pessoas com defici\u00eancia &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t08\/07\/2026 &#8211; 10:57 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1288997\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1288997\">\n<p><em>Marina Ramos \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Alex Manente defendeu a aprova\u00e7\u00e3o da proposta<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania (CCJ) da C\u00e2mara dos Deputados aprovou, em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span>, projeto que refor\u00e7a a prioridade no atendimento para cuidadores e familiares de pessoas com defici\u00eancia.<\/p>\n<p>A proposta altera a <a href=\"https:\/\/www2.camara.leg.br\/legin\/fed\/lei\/2000\/lei-10048-8-novembro-2000-376937-norma-pl.html\">Lei do Atendimento Priorit\u00e1rio<\/a> para determinar que o atendimento priorit\u00e1rio que \u00e9 estendido aos acompanhantes deve estar claro e expl\u00edcito nos informativos de identifica\u00e7\u00e3o e sinaliza\u00e7\u00e3o do servi\u00e7o.<\/p>\n<p>Por <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/prop_mostrarintegra?codteor=3152863&amp;filename=Parecer-CCJC-2026-06-25\">recomenda\u00e7\u00e3o do relator<\/a>, deputado Alex Manente (Cidadania-SP), foi aprovado o <span id=\"4098\" class=\"termoGlossario\" title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">substitutivo<\/span> da Comiss\u00e3o de Defesa dos Direitos das Pessoas com Defici\u00eancia para o Projeto de Lei 3505\/25, do deputado Amom Mandel (Republicanos-AM).<\/p>\n<p>A proposta seguir\u00e1 agora para an\u00e1lise do Senado, a menos que haja pedido para que seja votada tamb\u00e9m pelo Plen\u00e1rio da C\u00e2mara.<\/p>\n<p><strong>Proposta inicial<\/strong><br \/>O projeto original garantia o atendimento priorit\u00e1rio aos cuidadores familiares de pessoas com defici\u00eancia quando estivessem acompanhando a pessoa cuidada. No entanto, esse objetivo j\u00e1 se encontra previsto em normas em vigor.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 No\u00e9li Nobre<br \/>Edi\u00e7\u00e3o \u2013 Marcelo Oliveira<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1288993-comissao-aprova-projeto-que-reforca-prioridade-de-atendimento-para-cuidadores-de-pessoas-com-deficiencia\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>08\/07\/2026 &#8211; 10:57 \u00a0 Marina Ramos \/ C\u00e2mara dos Deputados Alex Manente defendeu a aprova\u00e7\u00e3o da proposta A Comiss\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/4006"}],"collection":[{"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=4006"}],"version-history":[{"count":0,"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/4006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/4007"}],"wp:attachment":[{"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=4006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=4006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canalsamba.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=4006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}